{"id":4439,"date":"2021-10-12T16:27:24","date_gmt":"2021-10-12T16:27:24","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?page_id=4439"},"modified":"2024-04-03T16:40:48","modified_gmt":"2024-04-03T16:40:48","slug":"contactanos","status":"publish","type":"page","link":"https:\/\/biodarma.com\/en\/contactanos","title":{"rendered":"CONTACT US"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4439\" class=\"elementor elementor-4439\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-7489718d elementor-section-full_width wd-section-stretch-content elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"7489718d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61615b09\" data-id=\"61615b09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1f024fc e-flex e-con-boxed e-con e-parent\" data-id=\"1f024fc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c47f958 wd-width-100 wd-nav-accordion-mb-on elementor-widget elementor-widget-wd_product_categories\" data-id=\"c47f958\" data-element_type=\"widget\" data-widget_type=\"wd_product_categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-cats products columns-3 wd-cats-element wd-carousel-container\" id=\"carousel-6a044605a2407\">\n\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product first\" data-loop=\"1\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\" aria-label=\"Emilia&#039;s Recipe\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"140\" src=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-general.png\" class=\"attachment-medium size-medium\" alt=\"Biodarma productos ecol\u00f3gicos deliciosos que te cuidan\" srcset=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-general.png 247w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-general-150x85.png 150w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-general-200x113.png 200w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-general-18x10.png 18w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tEmilia's Recipe\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\" aria-label=\"Product category recipe-from-emilia\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product\" data-loop=\"2\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\/con-datil\" aria-label=\"With date\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"140\" src=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma.png\" class=\"attachment-medium size-medium\" alt=\"Biodarma productos ecol\u00f3gicos deliciosos que te cuidan\" srcset=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma.png 247w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-150x85.png 150w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-200x113.png 200w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-18x10.png 18w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tWith date\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\/con-datil\" aria-label=\"Product category con-datil\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product\" data-loop=\"3\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\/sin-gluten\" aria-label=\"Gluten free\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"140\" src=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-SINGLUTEN.png\" class=\"attachment-medium size-medium\" alt=\"Biodarma productos ecol\u00f3gicos deliciosos que te cuidan\" srcset=\"https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-SINGLUTEN.png 247w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-SINGLUTEN-150x85.png 150w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-SINGLUTEN-200x113.png 200w, https:\/\/biodarma.com\/wp-content\/uploads\/2024\/02\/Biodarma-recetas-de-emilia-biodarma-SINGLUTEN-18x10.png 18w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tGluten free\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/biodarma.com\/en\/product-category\/receta-clasica-ultimas-unidades\/receta-de-emilia\/sin-gluten\" aria-label=\"Product category gluten-free\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-512da538 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"512da538\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a8efb54\" data-id=\"a8efb54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1304f714 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"1304f714\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-bordered wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">INFORMATION<br \/>\n<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8545f87 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8545f87\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">BIO DARMA, S.L.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edgono Industrial Finca Lacy, 03600 Elda, Alicante<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@biodarma.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">965378559<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10224f3 elementor-widget elementor-widget-google_maps\" data-id=\"10224f3\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Biodarma%20%7C%20Pasteler%C3%ADa%20bio%2C%20eco%20y%20vegana&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Biodarma | Organic, eco and vegan pastry shop\"\n\t\t\t\t\taria-label=\"Biodarma | Organic, eco and vegan pastry shop\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1faadd0a\" data-id=\"1faadd0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b5c3d8 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"3b5c3d8\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-bordered wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">SEND US AN EMAIL<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a812d6f elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"a812d6f\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"4439\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"a812d6f\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"CONT\u00c1CTANOSBiodarma\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"4439\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_cc5fbb3 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_cc5fbb3\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LdW8qopAAAAANDERH5D0x8LtFT40pPsCwOF1eiY\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send to<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gluten free (3) Emilia's Recipe (7) With dates (3) INFORMATION BIO DARMA, S.L. Pol\u00edgono Industrial Finca Lacy, 03600<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4439","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/pages\/4439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/comments?post=4439"}],"version-history":[{"count":5,"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/pages\/4439\/revisions"}],"predecessor-version":[{"id":17123,"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/pages\/4439\/revisions\/17123"}],"wp:attachment":[{"href":"https:\/\/biodarma.com\/en\/wp-json\/wp\/v2\/media?parent=4439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}